{"id":3017,"date":"2025-08-03T13:49:27","date_gmt":"2025-08-03T19:49:27","guid":{"rendered":"https:\/\/barberiamexico.com\/?page_id=3017"},"modified":"2026-04-08T07:24:07","modified_gmt":"2026-04-08T13:24:07","slug":"galeria","status":"publish","type":"page","link":"https:\/\/barberiamexico.com\/en\/galeria\/","title":{"rendered":"Gallery"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3017\" class=\"elementor elementor-3017\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-36ca6b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"36ca6b6\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fbbbf21 pxl-column-none\" data-id=\"fbbbf21\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-e886a9b elementor-widget elementor-widget-spacer\" data-id=\"e886a9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-357c1a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-bg-color-none pxl-section-overlay-none\" data-id=\"357c1a1\" data-element_type=\"section\" data-e-type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default\">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-08eef0d pxl-column-none\" data-id=\"08eef0d\" data-element_type=\"column\" data-e-type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-810afb1 elementor-widget elementor-widget-pxl_gallery_grid\" data-id=\"810afb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_gallery_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-grid-6a04a96ecde70 pxl-gallery-layout pxl-gallery-grid1 pxl-gallery-1 pxl-grid-nogap\">\r\n        <div class=\"pxl-grid-inner pxl-grid-masonry row\" data-gutter=\"15\">\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-06-at-22.08.00-2.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img fetchpriority=\"high\" decoding=\"async\" width=\"1066\" height=\"1600\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-06-at-22.08.00-2.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/barberiamexicoreforma-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img decoding=\"async\" width=\"1704\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/barberiamexicoreforma-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3899-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3899-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/03\/DSC4637-scaled-e1773169699998.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1135\" height=\"1323\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/03\/DSC4637-scaled-e1773169699998.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3934-scaled.jpg\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3934-scaled.jpg\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3869-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3869-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3926-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1704\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3926-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/fade-scaled-1.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1200\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/fade-scaled-1.webp\" class=\"no-lazyload attachment-full\" alt=\"corte de cabello y afeitado\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3856-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3856-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3689-1-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1704\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC3689-1-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/03\/DSC4589-scaled-e1773169292761.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"963\" height=\"1300\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/03\/DSC4589-scaled-e1773169292761.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC4033-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/DSC4033-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-17-at-12.22.35-AM-e1754250023271.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"962\" height=\"962\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-17-at-12.22.35-AM-e1754250023271.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-11-at-5.05.03-AM-e1754248978421.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1060\" height=\"1190\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-11-at-5.05.03-AM-e1754248978421.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-04-at-9.44.14-PM-2-e1754248667775.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1013\" height=\"920\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-04-at-9.44.14-PM-2-e1754248667775.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/07\/corte-de-cabello-ciudad-de-mexico-e1751631228451.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1138\" height=\"1374\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/07\/corte-de-cabello-ciudad-de-mexico-e1751631228451.webp\" class=\"no-lazyload attachment-full\" alt=\"barbero fernando\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/barberiaangelreforma.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1045\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/barberiaangelreforma.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/hair-salon-mx-300x300-1.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/hair-salon-mx-300x300-1.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/barber-shop-near-300x300-1.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/barber-shop-near-300x300-1.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-29-at-4.59.24-AM-e1754249959417.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-29-at-4.59.24-AM-e1754249959417.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/03\/ASL_E0097_291-e1754247493994.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"337\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/03\/ASL_E0097_291-e1754247493994.webp\" class=\"no-lazyload attachment-full\" alt=\"Cortes de cabello para hombre adaptados al estilo y preferencia de cada cliente\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/03\/PHOTO-2025-02-03-17-56-00-e1741972250698.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"319\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/03\/PHOTO-2025-02-03-17-56-00-e1741972250698.webp\" class=\"no-lazyload attachment-full\" alt=\"Cortes de cabello para hombre\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-03-at-2.06.58-AM.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1204\" height=\"1600\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-03-at-2.06.58-AM.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/07\/ASL_0133-rotated-e1751631474756.jpg\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"506\" height=\"732\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/07\/ASL_0133-rotated-e1751631474756.jpg\" class=\"no-lazyload attachment-full\" alt=\"barbero cortando cabello\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-18-at-11.49.44-PM-e1754250076462.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-18-at-11.49.44-PM-e1754250076462.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-11-at-11.11.08-PM-e1754249067295.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-11-at-11.11.08-PM-e1754249067295.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/03\/ASL_0006-scaled-e1741972441174.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"334\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/03\/ASL_0006-scaled-e1741972441174.webp\" class=\"no-lazyload attachment-full\" alt=\"low fade y los looks m\u00e1s modernos\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/barber-ciudad-de-mexicio-300x300-1.png\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/barber-ciudad-de-mexicio-300x300-1.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/barbershop-2-300x300-1.png\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/barbershop-2-300x300-1.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/ASL_0088-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/ASL_0088-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-05-at-12.17.53-AM-1-e1754249131610.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-07-05-at-12.17.53-AM-1-e1754249131610.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/barbernear-300x300-1.png\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/barbernear-300x300-1.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/ASL_0123-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/ASL_0123-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/ASL_0066-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/ASL_0066-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/barberiamx-scaled.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1707\" height=\"2560\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/barberiamx-scaled.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/barberia-en-la-ciudad.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1267\" height=\"1671\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/barberia-en-la-ciudad.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-03-at-2.17.44-AM.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1204\" height=\"1600\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/WhatsApp-Image-2025-08-03-at-2.17.44-AM.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/barberiamexicodf.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/barberiamexicodf.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/cortedepelohombre.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1365\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/cortedepelohombre.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\">\r\n                    <div class=\"item--inner\">\r\n                        <a href=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/cortemodernojpg.webp\" data-elementor-lightbox-slideshow=\"pxl-gallery-6a04a96ecde70\">\r\n                            <img loading=\"lazy\" decoding=\"async\" width=\"643\" height=\"1124\" src=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2025\/08\/cortemodernojpg.webp\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                            <div class=\"content-text\">\r\n                                Galer\u00eda Reforma                            <\/div>\r\n                        <\/a>\r\n                   <\/div>\r\n                <\/div>\r\n                        <div class=\"grid-sizer col-xl-3 col-lg-3 col-md-4 col-sm-6 col-6\"><\/div>\r\n        <\/div>\r\n    <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","_joinchat":[],"footnotes":""},"class_list":["post-3017","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Galer\u00eda - Reforma Barber Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/barberiamexico.com\/en\/galeria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galer\u00eda - Reforma Barber Shop\" \/>\n<meta property=\"og:description\" content=\"Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/barberiamexico.com\/en\/galeria\/\" \/>\n<meta property=\"og:site_name\" content=\"Reforma Barber Shop\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T13:24:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-06-at-22.08.00-2.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/galeria\\\/\",\"url\":\"https:\\\/\\\/barberiamexico.com\\\/galeria\\\/\",\"name\":\"Galer\u00eda - Reforma Barber Shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/galeria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/galeria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/barberiamexico.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-03-06-at-22.08.00-2.webp\",\"datePublished\":\"2025-08-03T19:49:27+00:00\",\"dateModified\":\"2026-04-08T13:24:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/galeria\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/barberiamexico.com\\\/galeria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/galeria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/barberiamexico.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-03-06-at-22.08.00-2.webp\",\"contentUrl\":\"https:\\\/\\\/barberiamexico.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/WhatsApp-Image-2026-03-06-at-22.08.00-2.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/galeria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/barberiamexico.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Galer\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/barberiamexico.com\\\/en\\\/\",\"name\":\"Reforma Barber Shop\",\"description\":\"Peluquer\u00eda masculina en ciudad de Mexico\",\"publisher\":{\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/barberiamexico.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/en\\\/#organization\",\"name\":\"Reforma Barber Shop\",\"url\":\"https:\\\/\\\/barberiamexico.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/barberiamexico.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-PNG.png\",\"contentUrl\":\"https:\\\/\\\/barberiamexico.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo-PNG.png\",\"width\":3502,\"height\":3502,\"caption\":\"Reforma Barber Shop\"},\"image\":{\"@id\":\"https:\\\/\\\/barberiamexico.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galer\u00eda - Reforma Barber Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/barberiamexico.com\/en\/galeria\/","og_locale":"en_US","og_type":"article","og_title":"Galer\u00eda - Reforma Barber Shop","og_description":"Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda Reforma Galer\u00eda [&hellip;]","og_url":"https:\/\/barberiamexico.com\/en\/galeria\/","og_site_name":"Reforma Barber Shop","article_modified_time":"2026-04-08T13:24:07+00:00","og_image":[{"url":"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-06-at-22.08.00-2.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/barberiamexico.com\/galeria\/","url":"https:\/\/barberiamexico.com\/galeria\/","name":"Galer\u00eda - Reforma Barber Shop","isPartOf":{"@id":"https:\/\/barberiamexico.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/barberiamexico.com\/galeria\/#primaryimage"},"image":{"@id":"https:\/\/barberiamexico.com\/galeria\/#primaryimage"},"thumbnailUrl":"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-06-at-22.08.00-2.webp","datePublished":"2025-08-03T19:49:27+00:00","dateModified":"2026-04-08T13:24:07+00:00","breadcrumb":{"@id":"https:\/\/barberiamexico.com\/galeria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/barberiamexico.com\/galeria\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/barberiamexico.com\/galeria\/#primaryimage","url":"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-06-at-22.08.00-2.webp","contentUrl":"https:\/\/barberiamexico.com\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-03-06-at-22.08.00-2.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/barberiamexico.com\/galeria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/barberiamexico.com\/"},{"@type":"ListItem","position":2,"name":"Galer\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/barberiamexico.com\/en\/#website","url":"https:\/\/barberiamexico.com\/en\/","name":"Reforma Barber Shop","description":"Peluquer\u00eda masculina en ciudad de Mexico","publisher":{"@id":"https:\/\/barberiamexico.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/barberiamexico.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/barberiamexico.com\/en\/#organization","name":"Reforma Barber Shop","url":"https:\/\/barberiamexico.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/barberiamexico.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/logo-PNG.png","contentUrl":"https:\/\/barberiamexico.com\/wp-content\/uploads\/2024\/10\/logo-PNG.png","width":3502,"height":3502,"caption":"Reforma Barber Shop"},"image":{"@id":"https:\/\/barberiamexico.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/barberiamexico.com\/en\/wp-json\/wp\/v2\/pages\/3017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barberiamexico.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/barberiamexico.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/barberiamexico.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/barberiamexico.com\/en\/wp-json\/wp\/v2\/comments?post=3017"}],"version-history":[{"count":37,"href":"https:\/\/barberiamexico.com\/en\/wp-json\/wp\/v2\/pages\/3017\/revisions"}],"predecessor-version":[{"id":3384,"href":"https:\/\/barberiamexico.com\/en\/wp-json\/wp\/v2\/pages\/3017\/revisions\/3384"}],"wp:attachment":[{"href":"https:\/\/barberiamexico.com\/en\/wp-json\/wp\/v2\/media?parent=3017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}